{"id":3154,"date":"2023-10-04T02:04:04","date_gmt":"2023-10-04T00:04:04","guid":{"rendered":"https:\/\/nuevaweb.cpl.es\/producto\/san-enrique-de-osso-maestro-y-sacerdote-9788498054347\/"},"modified":"2026-02-12T17:17:55","modified_gmt":"2026-02-12T16:17:55","slug":"san-enrique-de-osso-maestro-y-sacerdote-9788498054347","status":"publish","type":"product","link":"https:\/\/www.cpl.es\/ca\/producto\/san-enrique-de-osso-maestro-y-sacerdote-9788498054347\/","title":{"rendered":"San Enrique de Oss\u00f3, maestro y sacerdote"},"content":{"rendered":"<p>Un hombre entregado a Dios y a los dem\u00e1s, fundador de la Compa\u00f1\u00eda de Santa Teresa de Jes\u00fas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Molins, M.Victoria<\/p>\n","protected":false},"featured_media":3155,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[112,133,53,70,154],"product_tag":[],"class_list":{"0":"post-3154","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-santoral","7":"product_cat-santoral-any-liturgic-per-temes","8":"product_cat-santos-y-santas","9":"product_cat-sants-i-santes","10":"product_cat-vida-de-santos","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"acf":{"autor":"Molins, M.Victoria","codart":"112171","ediciones":"1","encuadernacion":"Grapado","fecha_de_publicacion":"20\/10\/2010","novedad":false,"paginas":"24","subtitulo":"","orden":"230","portada":false,"idioma":"spa","editorial":[{"ID":6736,"post_author":"2","post_date":"2023-10-06 08:35:24","post_date_gmt":"2023-10-06 06:35:24","post_content":"","post_title":"CPL","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"cpl","to_ping":"","pinged":"","post_modified":"2023-10-06 08:35:24","post_modified_gmt":"2023-10-06 06:35:24","post_content_filtered":"","post_parent":0,"guid":"https:\/\/nuevaweb.cpl.es\/editorial\/cpl\/","menu_order":0,"post_type":"editorial","post_mime_type":"","comment_count":"0","filter":"raw"}],"coleccion_num":"171"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>San Enrique de Oss\u00f3, maestro y sacerdote - CPL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cpl.es\/producto\/san-enrique-de-osso-maestro-y-sacerdote-9788498054347\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Enrique de Oss\u00f3, maestro y sacerdote - CPL\" \/>\n<meta property=\"og:description\" content=\"Molins, M.Victoria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cpl.es\/producto\/san-enrique-de-osso-maestro-y-sacerdote-9788498054347\/\" \/>\n<meta property=\"og:site_name\" content=\"CPL\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-12T16:17:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cpl.es\/wp-content\/uploads\/112171.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"416\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cpl.es\\\/producto\\\/san-enrique-de-osso-maestro-y-sacerdote-9788498054347\\\/\",\"url\":\"https:\\\/\\\/www.cpl.es\\\/producto\\\/san-enrique-de-osso-maestro-y-sacerdote-9788498054347\\\/\",\"name\":\"San Enrique de Oss\u00f3, maestro y sacerdote - CPL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cpl.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cpl.es\\\/producto\\\/san-enrique-de-osso-maestro-y-sacerdote-9788498054347\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cpl.es\\\/producto\\\/san-enrique-de-osso-maestro-y-sacerdote-9788498054347\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cpl.es\\\/wp-content\\\/uploads\\\/112171.jpg\",\"datePublished\":\"2023-10-04T00:04:04+00:00\",\"dateModified\":\"2026-02-12T16:17:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cpl.es\\\/producto\\\/san-enrique-de-osso-maestro-y-sacerdote-9788498054347\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cpl.es\\\/producto\\\/san-enrique-de-osso-maestro-y-sacerdote-9788498054347\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.cpl.es\\\/producto\\\/san-enrique-de-osso-maestro-y-sacerdote-9788498054347\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cpl.es\\\/wp-content\\\/uploads\\\/112171.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cpl.es\\\/wp-content\\\/uploads\\\/112171.jpg\",\"width\":280,\"height\":416,\"caption\":\"112171.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cpl.es\\\/producto\\\/san-enrique-de-osso-maestro-y-sacerdote-9788498054347\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.cpl.es\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cat\u00e0leg\",\"item\":\"https:\\\/\\\/www.cpl.es\\\/ca\\\/cataleg\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"San Enrique de Oss\u00f3, maestro y sacerdote\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cpl.es\\\/#website\",\"url\":\"https:\\\/\\\/www.cpl.es\\\/\",\"name\":\"CPL\",\"description\":\"Centre de Pastoral Lit\u00fargica de Barcelona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cpl.es\\\/#organization\"},\"alternateName\":\"Centre de Pastoral Lit\u00fargica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cpl.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cpl.es\\\/#organization\",\"name\":\"Centre de Pastoral Lit\u00fargica\",\"alternateName\":\"Centre de Pastoral Lit\u00fargica de Barcelona\",\"url\":\"https:\\\/\\\/www.cpl.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.cpl.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cpl.es\\\/wp-content\\\/uploads\\\/logo-cpl.svg\",\"contentUrl\":\"https:\\\/\\\/www.cpl.es\\\/wp-content\\\/uploads\\\/logo-cpl.svg\",\"caption\":\"Centre de Pastoral Lit\u00fargica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cpl.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"San Enrique de Oss\u00f3, maestro y sacerdote - CPL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cpl.es\/producto\/san-enrique-de-osso-maestro-y-sacerdote-9788498054347\/","og_locale":"ca_ES","og_type":"article","og_title":"San Enrique de Oss\u00f3, maestro y sacerdote - CPL","og_description":"Molins, M.Victoria","og_url":"https:\/\/www.cpl.es\/producto\/san-enrique-de-osso-maestro-y-sacerdote-9788498054347\/","og_site_name":"CPL","article_modified_time":"2026-02-12T16:17:55+00:00","og_image":[{"width":280,"height":416,"url":"https:\/\/www.cpl.es\/wp-content\/uploads\/112171.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cpl.es\/producto\/san-enrique-de-osso-maestro-y-sacerdote-9788498054347\/","url":"https:\/\/www.cpl.es\/producto\/san-enrique-de-osso-maestro-y-sacerdote-9788498054347\/","name":"San Enrique de Oss\u00f3, maestro y sacerdote - CPL","isPartOf":{"@id":"https:\/\/www.cpl.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cpl.es\/producto\/san-enrique-de-osso-maestro-y-sacerdote-9788498054347\/#primaryimage"},"image":{"@id":"https:\/\/www.cpl.es\/producto\/san-enrique-de-osso-maestro-y-sacerdote-9788498054347\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cpl.es\/wp-content\/uploads\/112171.jpg","datePublished":"2023-10-04T00:04:04+00:00","dateModified":"2026-02-12T16:17:55+00:00","breadcrumb":{"@id":"https:\/\/www.cpl.es\/producto\/san-enrique-de-osso-maestro-y-sacerdote-9788498054347\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cpl.es\/producto\/san-enrique-de-osso-maestro-y-sacerdote-9788498054347\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.cpl.es\/producto\/san-enrique-de-osso-maestro-y-sacerdote-9788498054347\/#primaryimage","url":"https:\/\/www.cpl.es\/wp-content\/uploads\/112171.jpg","contentUrl":"https:\/\/www.cpl.es\/wp-content\/uploads\/112171.jpg","width":280,"height":416,"caption":"112171.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cpl.es\/producto\/san-enrique-de-osso-maestro-y-sacerdote-9788498054347\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cpl.es\/ca\/"},{"@type":"ListItem","position":2,"name":"Cat\u00e0leg","item":"https:\/\/www.cpl.es\/ca\/cataleg\/"},{"@type":"ListItem","position":3,"name":"San Enrique de Oss\u00f3, maestro y sacerdote"}]},{"@type":"WebSite","@id":"https:\/\/www.cpl.es\/#website","url":"https:\/\/www.cpl.es\/","name":"CPL","description":"Centre de Pastoral Lit\u00fargica de Barcelona","publisher":{"@id":"https:\/\/www.cpl.es\/#organization"},"alternateName":"Centre de Pastoral Lit\u00fargica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cpl.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.cpl.es\/#organization","name":"Centre de Pastoral Lit\u00fargica","alternateName":"Centre de Pastoral Lit\u00fargica de Barcelona","url":"https:\/\/www.cpl.es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.cpl.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.cpl.es\/wp-content\/uploads\/logo-cpl.svg","contentUrl":"https:\/\/www.cpl.es\/wp-content\/uploads\/logo-cpl.svg","caption":"Centre de Pastoral Lit\u00fargica"},"image":{"@id":"https:\/\/www.cpl.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.cpl.es\/ca\/wp-json\/wp\/v2\/product\/3154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cpl.es\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.cpl.es\/ca\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cpl.es\/ca\/wp-json\/wp\/v2\/media\/3155"}],"wp:attachment":[{"href":"https:\/\/www.cpl.es\/ca\/wp-json\/wp\/v2\/media?parent=3154"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.cpl.es\/ca\/wp-json\/wp\/v2\/product_brand?post=3154"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.cpl.es\/ca\/wp-json\/wp\/v2\/product_cat?post=3154"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.cpl.es\/ca\/wp-json\/wp\/v2\/product_tag?post=3154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}